{"id":508,"date":"2019-08-20T10:46:31","date_gmt":"2019-08-20T10:46:31","guid":{"rendered":"https:\/\/botam.eu\/jak-zyskac-zaufanie-klienta-w-logistyce\/"},"modified":"2020-04-16T21:01:12","modified_gmt":"2020-04-16T19:01:12","slug":"in-der-logistik-kann-man-kein-kundenvertrauen-kaufen","status":"publish","type":"post","link":"https:\/\/botam.eu\/de\/in-der-logistik-kann-man-kein-kundenvertrauen-kaufen\/","title":{"rendered":"In der Logistik kann man kein Kundenvertrauen kaufen"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/W-logistyce-nie-da-si\u0119-kupi\u0107-zaufania-klienta.jpg\"><img decoding=\"async\" src=\"https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/W-logistyce-nie-da-si\u0119-kupi\u0107-zaufania-klienta.jpg\" alt=\"Droga na zboczu g\u00f3ry z widokiem na morze - zaufanie w logistyce\" class=\"wp-image-416\"\/><\/a><\/figure><\/div>\n\n\n\n<p>Man sagte immer, dass Gesch\u00e4fte mit Menschen gemacht werden, die man mag. M\u00f6chten Sie aber gemeinsame Unternehmen mit einem Lieferanten eingehen, dem Sie nicht vertrauen? In der Logistikbranche, insbesondere bei der Lieferung von Produkten im System Just In Time ist Vertrauen der Schl\u00fcssel zum Aufbau langfristiger Gesch\u00e4ftsbeziehungen. Sie k\u00f6nnen es nicht kaufen oder aufbauen, indem Sie einmal im Jahr eine Weihnachtskarte senden, selbst wenn die W\u00fcnsche handgeschrieben sind. Warum Vertrauen so wichtig ist und wie es in der Logistikbranche entwickelt werden kann, lesen Sie in diesem Artikel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Was ist Vertrauen in der Just In Time-Lieferbranche?<\/strong><\/h2>\n\n\n\n<p>Vertrauen in der Logistik ist nichts anderes als das Vertrauen, dass der anvertraute Auftrag mit der gebotenen Sorgfalt und yu richtiger&nbsp; Zeitausgef\u00fchrt wird. Es ist auch ein Glaube an das Handeln des Transportdienstleisters, das durch die beste Absicht vorgegeben ist, d.h. eine angemessene Sicherung der Waren w\u00e4hrend des Transports, die F\u00e4higkeit der L\u00f6sung von problematischen Situationen w\u00e4hrend der Warenverladung usw.<\/p>\n\n\n\n<p>Vertrauen ist das Ergebnis einer allm\u00e4hlich aufgebauten Glaubw\u00fcrdigkeit, d.h. einer st\u00e4ndigen Realisierung von Transportauftr\u00e4gen gem\u00e4\u00df den angenommenen Annahmen. Aus formaler Sicht sch\u00fctzt der schriftliche Vertrag die Interessen der Parteien, gibt dem Kunden jedoch nicht so viel Ruhe und Sicherheitsgef\u00fchl wie das Vertrauen in den Anbieter von Logistikdienstleistungen. Denn wenn die Produktionslinie wegen fehlender Komponente gestoppt wird, entsteht nicht nur ein finanzieller Verlust. Es ist auch ein gro\u00dfer Stress f\u00fcr den Supply Chain Manager, der sp\u00e4ter auf keine Weise kompensiert werden kann.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Wie kann man durch Just In Time-Lieferungen Vertrauen gewinnen?<\/strong><\/h2>\n\n\n\n<p><strong>Zuallererst die Fahrzeugflotte.<\/strong> Die Bef\u00f6rderung von G\u00fctern mit relativ neuen Autos bietet ein h\u00f6heres Ma\u00df an Zuverl\u00e4ssigkeit. F\u00fcgen Sie dazu die geeignete Fahrzeugausr\u00fcstung, L\u00f6sungen zur Erh\u00f6hung der Ladekapazit\u00e4t, z. B. zweist\u00f6ckiger Boden oder Fahrzeugmarkierung mit einer einheitlichen visuellen Identit\u00e4t hinzu, und gewinnen Sie in den Augen des Kunden zus\u00e4tzliche Punkte.<\/p>\n\n\n\n<p><strong>Zweitens die Auftragsabwicklung. <\/strong>Sehr wichtig ist hier die pers\u00f6nliche Kultur der Mitarbeiter des Transportunternehmens und ihre F\u00e4higkeit, in Stresssituationen k\u00fchl zu bleiben, die in dieser Branche h\u00e4ufig sind. <br>\nBei der Ausf\u00fchrung ausl\u00e4ndischer Kundenauftr\u00e4ge ist es auch die F\u00e4higkeit, die Fremdsprache in Sprache und Schrift zu beherrschen. Dadurch wird er sich einfach wohl f\u00fchlen. <br>\nWichtig sind auch Sachen, die trivial scheinen. Zum Beispiel gibt ihm eine E-Mail mit R\u00fcckmeldung zur Anreisezeit oder Transparenz, die sich daraus ergibt, dass dem Kunden die geografische Position des Autos mitgeteilt wird, das die Waren transportiert, ein Gef\u00fchl der Kontrolle \u00fcber die Situation.<\/p>\n\n\n\n<p><strong>Drittens das Bewusstsein, dass jeder f\u00fcr das Vertrauen in ein Transportunternehmen arbeitet:<\/strong> vom Mitarbeiter, der Bestellungen annimmt, durch den Fahrer, bis zum Buchhalter, der die Rechnung ausstellt oder versp\u00e4tete Zahlungen einzieht. Wenn die Mitarbeiter des Unternehmens das Gef\u00fchl haben, dass der Chef ihnen vertraut, werden sie versuchen, dieses Vertrauen nicht zu entt\u00e4uschen. Deshalb ist es so wichtig, eine gesunde Atmosph\u00e4re im Unternehmen aufzubauen und sich um die Mitarbeiter zu k\u00fcmmern.<\/p>\n\n\n\n<p><strong>Viertens und am wichtigsten &#8211; der erste Eindruck wird nur einmal gemacht.<\/strong> Bei der Realisierung der ersten Just In Time-Lieferung gibt der Kunde dem Spediteur einen gro\u00dfes Vertrauensvorschuss mit reinen Gesch\u00e4ftserwartungen. Bei der Auslieferung eines solchen Auftrags, lohnt es sich daher, sie so gut wie m\u00f6glich auszuf\u00fchren und damit zu beweisen, dass man ein vertrauensw\u00fcrdiges Unternehmen ist. Nur so wenig und gleichzeitig so viel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Langfristige Zusammenarbeit kann nur auf Vertrauen aufgebaut werden<\/strong><\/h2>\n\n\n\n<p>Der Kunde, der sich f\u00fcr den Just In Time-Dienstleister entscheidet, hat h\u00e4ufig das sprichw\u00f6rtliche Messer am Hals und er hat keine Zeit, eine Ausschreibung f\u00fcr einen Transportdienstleister vorzubereiten. Daher m\u00f6chte er die Ausf\u00fchrung des Auftrags jemandem anvertrauen, der zuverl\u00e4ssig und m\u00fcndlich ist und seine Arbeit gut macht, also jemandem, der einfach vertrauensw\u00fcrdig &#8211; und nicht unbedingt der billigste, ist.<\/p>\n\n\n\n<p>Hervorzuheben ist, dass der Kunde dank des entwickelten Vertrauens bereit ist, die Dienstleistungen eines auf Just In Time-Lieferungen spezialisierten Unternehmens anderen zu empfehlen. Er kann auch jede zuf\u00e4llige Situation verzeihen, auf die der Lieferant keinen direkten Einfluss hatte.&nbsp;<\/p>\n\n\n\n<p>Zusammenfassend muss man sich in der Logistik nicht m\u00f6gen &#8211; obwohl es den t\u00e4glichen Kontakt erleichtert. Die wichtigere W\u00e4hrung ist das Vertrauen, das dem Kunden ein Gef\u00fchl der echten Unterst\u00fctzung in jeder, selbst der schwierigsten Situation gibt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Man sagte immer, dass Gesch\u00e4fte mit Menschen gemacht werden, die man mag. M\u00f6chten Sie aber gemeinsame Unternehmen mit einem Lieferanten eingehen, dem Sie nicht vertrauen? In der Logistikbranche, insbesondere bei&hellip;<\/p>\n","protected":false},"author":1,"featured_media":509,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[58],"tags":[42,74,43,75,76,44,77,41],"class_list":["post-508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de","tag-jak-zdobyc-zaufanie-klienta","tag-jak-zdobyc-zaufanie-klienta-de","tag-zaufanie-w-dostawach-just-in-time","tag-zaufanie-w-dostawach-just-in-time-de","tag-zaufanie-w-logistyce-de","tag-zaufanie-w-logistyce","tag-zaufany-dostawca-just-in-time-de","tag-zaufany-dostawca-just-in-time"],"acf":[],"featured_image_urls_v2":{"full":["https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/w-logistyce-nie-da-sie-kupic-zaufania-klienta.jpg",820,312,false],"thumbnail":["https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/w-logistyce-nie-da-sie-kupic-zaufania-klienta-150x150.jpg",150,150,true],"medium":["https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/w-logistyce-nie-da-sie-kupic-zaufania-klienta-300x114.jpg",300,114,true],"medium_large":["https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/w-logistyce-nie-da-sie-kupic-zaufania-klienta-768x292.jpg",768,292,true],"large":["https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/w-logistyce-nie-da-sie-kupic-zaufania-klienta.jpg",820,312,false],"1536x1536":["https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/w-logistyce-nie-da-sie-kupic-zaufania-klienta.jpg",820,312,false],"2048x2048":["https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/w-logistyce-nie-da-sie-kupic-zaufania-klienta.jpg",820,312,false],"post-thumbnail":["https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/w-logistyce-nie-da-sie-kupic-zaufania-klienta.jpg",820,312,false],"thumbnail_square":["https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/w-logistyce-nie-da-sie-kupic-zaufania-klienta-526x312.jpg",526,312,true],"banner":["https:\/\/botam.eu\/wp-content\/uploads\/2019\/08\/w-logistyce-nie-da-sie-kupic-zaufania-klienta.jpg",820,312,false]},"post_excerpt_stackable_v2":"<p>Man sagte immer, dass Gesch\u00e4fte mit Menschen gemacht werden, die man mag. M\u00f6chten Sie aber gemeinsame Unternehmen mit einem Lieferanten eingehen, dem Sie nicht vertrauen? In der Logistikbranche, insbesondere bei der Lieferung von Produkten im System Just In Time ist Vertrauen der Schl\u00fcssel zum Aufbau langfristiger Gesch\u00e4ftsbeziehungen. Sie k\u00f6nnen es nicht kaufen oder aufbauen, indem Sie einmal im Jahr eine Weihnachtskarte senden, selbst wenn die W\u00fcnsche handgeschrieben sind. Warum Vertrauen so wichtig ist und wie es in der Logistikbranche entwickelt werden kann, lesen Sie in diesem Artikel. Was ist Vertrauen in der Just In Time-Lieferbranche? Vertrauen in der Logistik ist&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/botam.eu\/de\/kategoria\/news-de\/\" rel=\"category tag\">News<\/a>","author_info_v2":{"name":"admin@botam","url":"https:\/\/botam.eu\/de\/author\/adminbotam\/"},"comments_num_v2":"0 comments","_links":{"self":[{"href":"https:\/\/botam.eu\/de\/wp-json\/wp\/v2\/posts\/508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/botam.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/botam.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/botam.eu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/botam.eu\/de\/wp-json\/wp\/v2\/comments?post=508"}],"version-history":[{"count":1,"href":"https:\/\/botam.eu\/de\/wp-json\/wp\/v2\/posts\/508\/revisions"}],"predecessor-version":[{"id":511,"href":"https:\/\/botam.eu\/de\/wp-json\/wp\/v2\/posts\/508\/revisions\/511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/botam.eu\/de\/wp-json\/wp\/v2\/media\/509"}],"wp:attachment":[{"href":"https:\/\/botam.eu\/de\/wp-json\/wp\/v2\/media?parent=508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/botam.eu\/de\/wp-json\/wp\/v2\/categories?post=508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/botam.eu\/de\/wp-json\/wp\/v2\/tags?post=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}